{"id":10133,"date":"2025-02-19T13:12:53","date_gmt":"2025-02-19T11:12:53","guid":{"rendered":"https:\/\/setlementtiasunnot.fi\/company"},"modified":"2026-02-06T11:06:42","modified_gmt":"2026-02-06T09:06:42","slug":"company","status":"publish","type":"page","link":"https:\/\/setlementtiasunnot.fi\/en\/company","title":{"rendered":"Company"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;6849&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;10%&#8221; top_padding_tablet=&#8221;10%&#8221; bottom_padding_tablet=&#8221;15%&#8221; bottom_padding_phone=&#8221;20%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#000000&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;175&#8243; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;waves&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;h1&#8243; text_color=&#8221;#ffffff&#8221; text_direction=&#8221;ltr&#8221;]\n<h1>Company<\/h1>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#ffffff&#8221; text_direction=&#8221;ltr&#8221; font_line_height=&#8221;1.3&#8243; font_size_desktop=&#8221;20&#8243;]<strong>Founded in 2000, Setlementtiasunnot builds homes, communities, and a sustainable future. We offer affordable rental homes and communal neighborhoods in seven cities. <\/strong>[\/nectar_responsive_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; text=&#8221;Learn more about our practices&#8221; url=&#8221;#meista&#8221; margin_top=&#8221;20&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;8%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;8%&#8221; left_padding_tablet=&#8221;0&#8243; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; top_margin=&#8221;5%&#8221; constrain_group_7=&#8221;yes&#8221; bottom_margin=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;meista&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-md-2\/5&#8243;][image_with_animation image_url=&#8221;3294&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;175%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-md-3\/5&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1504128844236{margin-right: -1px !important;}&#8221;][vc_column_inner column_padding=&#8221;padding-10-percent&#8221; column_padding_tablet=&#8221;padding-5-percent&#8221; column_padding_phone=&#8221;padding-3-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffedc8&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;What&#039;s Important to Us&#8221; font_container=&#8221;tag:h3|text_align:left|color:%23284c79&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_custom_heading text=&#8221;We offer our residents affordable homes and communal neighborhoods. Our values are community, ecology, and economy. &#8221; font_container=&#8221;tag:p|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; icon_family=&#8221;none&#8221; text=&#8221;Read more about us&#8221; margin_right=&#8221;10&#8243; url=&#8221;#info&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;8%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;8%&#8221; left_padding_tablet=&#8221;0&#8243; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; bottom_margin=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-md-3\/5&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1504128844236{margin-right: -1px !important;}&#8221;][vc_column_inner column_padding=&#8221;padding-10-percent&#8221; column_padding_tablet=&#8221;padding-5-percent&#8221; column_padding_phone=&#8221;padding-3-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#d7f0e0&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Pioneer in Communal Living&#8221; font_container=&#8221;tag:h3|text_align:left|color:%23284c79&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_custom_heading text=&#8221;Our buildings offer space for togetherness, shared activities, and neighborly help. Everyone has the opportunity to belong. All our buildings have various common areas for residents&#039; shared activities.  &#8221; font_container=&#8221;tag:p|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; icon_family=&#8221;none&#8221; text=&#8221;Read more about community&#8221; margin_right=&#8221;10&#8243; url=&#8221;\/yhtio\/yhteisollisyys&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-md-2\/5&#8243;][image_with_animation image_url=&#8221;7006&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;175%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;8%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;8%&#8221; left_padding_tablet=&#8221;0&#8243; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; top_margin=&#8221;5%&#8221; constrain_group_7=&#8221;yes&#8221; bottom_margin=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-md-2\/5&#8243;][image_with_animation image_url=&#8221;6245&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;175%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-md-3\/5&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1504128844236{margin-right: -1px !important;}&#8221;][vc_column_inner column_padding=&#8221;padding-10-percent&#8221; column_padding_tablet=&#8221;padding-5-percent&#8221; column_padding_phone=&#8221;padding-3-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffedc8&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Responsibility&#8221; font_container=&#8221;tag:h3|text_align:left|color:%23284c79&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_custom_heading text=&#8221;With us, you can live responsibly. We are a socially, ecologically, and economically responsible operator. &#8221; font_container=&#8221;tag:p|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; icon_family=&#8221;none&#8221; text=&#8221;Read more&#8221; margin_right=&#8221;10&#8243; url=&#8221;\/yhtio\/vastuullisuus&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;info&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][toggles style=&#8221;minimal_shadow&#8221; border_radius=&#8221;none&#8221;][toggle color=&#8221;Extra-Color-1&#8243; heading_tag=&#8221;h3&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Setlementti\u00adasunnot Oy&#8221;][vc_row_inner column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4>Pioneer in Communal Living<\/h4>\n<p>Setlementtiasunnot Oy builds homes, communities, and a sustainable future. We offer affordable rental homes and communal neighborhoods in seven cities.  <span data-teams=\"true\">We are known for our blocks, and we are a pioneer in block construction in Finland.<\/span><\/p>\n<p>Our goal is to be the most desired landlord for residents and to develop housing that is ecologically, socially, and economically sustainable. We are a non-profit organization approved by <a href=\"https:\/\/www.varke.fi\/\" target=\"_blank\" rel=\"noopener\">Varken<\/a> (formerly ARA), owned by the politically and religiously independent <a href=\"https:\/\/setlementti.fi\/\" target=\"_blank\" rel=\"noopener\">Finnish Settlement Federation<\/a>. <\/p>\n<h4>Our Mission<\/h4>\n<p>We offer affordable homes and communal neighborhoods.<\/p>\n<h4>Our Values<\/h4>\n<p>Our values are community, ecology, and economy, for which we are known and which guide our operations.<\/p>\n<h4><span data-teams=\"true\">Homes, blocks, and communities with over two decades of experience<\/span><\/h4>\n<p>Founded in 2000, Setlementtiasunnot owns 21 rental buildings with over 1900 homes and approximately 2200 residents. We offer more than just a roof over your head. We build living environments where neighbors know each other, and daily life is smooth and meaningful.  <\/p>\n<p>All our buildings have a resident common room with a shared living room and kitchen. Many of our properties also have a sauna, gym, laundry room, and for example, a music room, workshop, or auditorium. These facilities are available to all our residents, and the common room can also be reserved for private use, such as parties or other important life moments.  <\/p>\n<p>Our buildings are diverse, housing people of different ages and life situations. They also include special groups, such as intellectually disabled and elderly residents, whose daily lives are supported by external service providers. <\/p>\n<p>Instead of individual buildings, we build entire blocks together with cities and our partners. Our communal blocks combine different housing types, age groups, and life situations. The heart of the block is a shared courtyard, surrounded by homes, common areas, and services. Natural encounters arise in daily life, and services provided by our partners enrich the neighborhood. We are a pioneer in block living in Finland and proud of it.    <\/p>\n<p>We openly and boldly develop our operations together with residents and partners. We utilize digital solutions, such as the <a href=\"https:\/\/setlementtiasunnot.fi\/talojen-palvelut\">Kerro application<\/a> and <a href=\"https:\/\/setlementtiasunnot.fi\/en\/resident-pages\">resident pages<\/a>, which streamline communication and service use. <\/p>\n<p>We believe that the best solutions are created through cooperation, now and in the future.[\/vc_column_text][image_with_animation image_url=&#8221;7254&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; bottom_position_desktop=&#8221;0&#8243; margin_bottom=&#8221;30&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4>Our Board Members<\/h4>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Eero Pentti<\/strong><br \/>\nChairman<\/p>\n<p><strong>Raimo H\u00e4t\u00e4l\u00e4<\/strong><br \/>\nVice Chairman<\/p>\n<p><strong>Sannaleena H\u00e4rk\u00f6nen<\/strong><br \/>\nMember<\/p>\n<p><strong>Raija Anjala<\/strong><br \/>\nMember[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Jussi Kemppainen<\/strong><br \/>\nMember<\/p>\n<p><strong>Antti Kuusiniemi<\/strong><br \/>\nMember<br \/>\nResident Representative<\/p>\n<p><strong>Matti Siitonen<\/strong><br \/>\nMember<br \/>\nResident Representative[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/toggle][\/toggles][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;info&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][toggles style=&#8221;minimal_shadow&#8221; border_radius=&#8221;none&#8221;][toggle color=&#8221;Extra-Color-1&#8243; heading_tag=&#8221;h3&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Setlementti\u00adasunnot Oy&#8221;][vc_row_inner column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Setlementtiasunnot Oy, founded in 2000, is a community builder, a multi-skilled provider of housing services, and a producer of socially sustainable housing. Currently, we have 21 rental buildings, slightly over 1900 homes, and approximately 2200 residents in seven different cities. <\/p>\n<p>We are a socially responsible operator. We offer affordable homes and communal neighborhoods. Our operations are ecological and economical.  <\/p>\n<p>We are a non-profit organization approved by Varken (formerly ARA) and offer rental homes in accordance with its resident selection guidelines. Our owner is the politically and religiously independent <a href=\"https:\/\/setlementti.fi\/\" target=\"_blank\" rel=\"noopener\">Finnish Settlement Federation<\/a>. <\/p>\n<h4><strong>Pioneer in Block Construction<\/strong><\/h4>\n<p>In addition to individual buildings, we construct entire blocks with our partners. Our company is a pioneer in communal block living in Finland. The block, surrounding a shared courtyard, features various housing types and resident groups. Residents have diverse meeting places in their daily lives, both in the building&#8217;s common areas and in the courtyard. Collaborative partners create various services within the block.    <\/p>\n<h4 class=\"vc_custom_heading vc_do_custom_heading\">Community at the Core<\/h4>\n<p>We strongly invest in community. All our buildings have common areas, including resident common rooms and shared kitchens, saunas, and gyms, available to residents and providing additional space. Our buildings also house special groups, such as intellectually disabled individuals, who are supported by external service providers.  <\/p>\n<p>We effectively utilize digitalization in both our operations and with residents. The Kerro application and resident pages serve as communication and booking tools. <\/p>\n<p>We boldly develop our operations together with our residents and partners.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/toggle][toggle color=&#8221;Extra-Color-1&#8243; heading_tag=&#8221;h3&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Board&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Eero Pentti<\/strong><br \/>\nChairman<\/p>\n<p><strong>Raimo H\u00e4t\u00e4l\u00e4<\/strong><br \/>\nVice Chairman<\/p>\n<p><strong>Mikko Santavuori<\/strong><br \/>\nMember<\/p>\n<p><strong>Satu Meht\u00e4l\u00e4<\/strong><br \/>\nMember<\/p>\n<p><strong>Jussi Kemppainen<\/strong><br \/>\nMember<\/p>\n<p><strong>Antti Kuusiniemi<\/strong><br \/>\nMember<br \/>\nResident Representative<\/p>\n<p><strong>Matti Siitonen<\/strong><br \/>\nMember<br \/>\nResident Representative[\/vc_column_text][\/toggle][\/toggles][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;info&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][toggles style=&#8221;minimal_shadow&#8221; border_radius=&#8221;none&#8221;][toggle color=&#8221;Extra-Color-1&#8243; heading_tag=&#8221;h3&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Setlementti\u00adasunnot Oy&#8221;][vc_row_inner column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Setlementtiasunnot Oy, founded in 2000, is a community builder, a multi-skilled provider of housing services, and a producer of socially sustainable housing. Currently, we have 21 rental buildings, slightly over 1900 homes, and approximately 2200 residents in seven different cities. <\/p>\n<p>We are a socially responsible operator. We offer affordable homes and communal neighborhoods. Our operations are ecological and economical.  <\/p>\n<p>We are a non-profit organization approved by ARA and offer rental homes in accordance with ARA&#8217;s resident selection guidelines. Our owner is the politically and religiously independent <a href=\"https:\/\/setlementti.fi\/\" target=\"_blank\" rel=\"noopener\">Finnish Settlement Federation<\/a>. <\/p>\n<h4><strong>Pioneer in Block Construction<\/strong><\/h4>\n<p>In addition to individual buildings, we construct entire blocks with our partners. Our company is a pioneer in communal block living in Finland. The block, surrounding a shared courtyard, features various housing types and resident groups. Residents have diverse meeting places in their daily lives, both in the building&#8217;s common areas and in the courtyard. Collaborative partners create various services within the block.    <\/p>\n<p>We strongly invest in community. All our buildings have common areas, including resident common rooms and shared kitchens, saunas, and gyms, available to residents and providing additional space. Our buildings also house special groups, such as intellectually disabled individuals, who are supported by external service providers.  <\/p>\n<p>We effectively utilize digitalization in both our operations and with residents. The Kerro application and resident pages serve as communication and booking tools. <\/p>\n<p>We boldly develop our operations together with our residents and partners.[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<em>By clicking the YouTube video, you accept <a href=\"https:\/\/policies.google.com\/?hl=fi\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">YouTube\/Google&#8217;s terms of service<\/a>.<\/em>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=WUda8m5Pub8&#8243; css=&#8221;&#8221;][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=RoXVX5btZzo&#8221; css=&#8221;&#8221;][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=fgXkiubbgys&#8221; css=&#8221;&#8221;][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=V9_aW7lc6J4&#8243; css=&#8221;&#8221;][\/vc_column_inner][\/vc_row_inner][\/toggle][toggle color=&#8221;Extra-Color-1&#8243; heading_tag=&#8221;h3&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Strategy&#8221;][vc_column_text][\/vc_column_text][\/toggle][toggle color=&#8221;Extra-Color-1&#8243; heading_tag=&#8221;h3&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Board&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Eero Pentti<\/strong><br \/>\nChairman<\/p>\n<p><strong>Raimo H\u00e4t\u00e4l\u00e4<\/strong><br \/>\nVice Chairman<\/p>\n<p><strong>Mikko Santavuori<\/strong><br \/>\nMember<\/p>\n<p><strong>Satu Meht\u00e4l\u00e4<\/strong><br \/>\nMember<\/p>\n<p><strong>Jussi Kemppainen<\/strong><br \/>\nMember<\/p>\n<p><strong>Antti Kuusiniemi<\/strong><br \/>\nMember<br \/>\nResident Representative<\/p>\n<p><strong>Matti Siitonen<\/strong><br \/>\nMember<br \/>\nResident Representative[\/vc_column_text][\/toggle][\/toggles][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;info&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][toggles style=&#8221;minimal_shadow&#8221; border_radius=&#8221;none&#8221;][toggle color=&#8221;Extra-Color-1&#8243; heading_tag=&#8221;h4&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Setlementti\u00adasunnot Oy&#8221;][vc_row_inner column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Setlementtiasunnot Oy, founded in 2000, is a community builder, a multi-skilled provider of housing services, and a producer of socially sustainable housing. Currently, we have 21 rental buildings, slightly over 1900 homes, and approximately 2200 residents in seven different cities. <\/p>\n<p>Our operations are based on community, ecology, and economy, as well as the needs of residents and society. All our buildings have varying common areas, including resident common rooms and shared kitchens, saunas, and gyms, available to residents and providing additional space. <\/p>\n<p>In addition to individual buildings, we construct entire blocks with our partners, where functions and structures are designed and implemented with the entire block and neighborhood in mind, supporting community, ecology, and economy.<\/p>\n<p>We have a responsible partner network in construction, maintenance, and resident activities. Our partners provide diverse services in our buildings; a key partner is the settlement organizations. We effectively utilize digitalization in both our operations and with residents. The Kerro application and resident pages serve as communication and booking tools.   <\/p>\n<p>We are a non-profit organization approved by ARA and offer rental homes in accordance with ARA&#8217;s resident selection guidelines. Our buildings also house special groups, such as intellectually disabled or mental health rehabilitants, who are supported by external service providers. <\/p>\n<p>The Finnish Settlement Federation is the owner. Setlementtiasunnot Oy is a member of Arvoliitto, the association of social enterprises. <\/p>\n<p>We continuously and boldly develop our operations together with our residents and partners.[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<em>Watch videos on YouTube by clicking the image.<br \/>\nNote: By doing so, you accept <a href=\"https:\/\/policies.google.com\/?hl=fi\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">YouTube\/Google&#8217;s terms of service<\/a>. <\/em>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=WUda8m5Pub8&#8243; css=&#8221;&#8221;][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=RoXVX5btZzo&#8221; css=&#8221;&#8221;][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=fgXkiubbgys&#8221; css=&#8221;&#8221;][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=V9_aW7lc6J4&#8243; css=&#8221;&#8221;][\/vc_column_inner][\/vc_row_inner][\/toggle][toggle color=&#8221;Extra-Color-1&#8243; heading_tag=&#8221;h4&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Community&#8221;][vc_row_inner column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Happiness is a good neighbor<\/strong><\/p>\n<ul>\n<li>All our buildings have various common areas, including resident common rooms, a gym, and a workshop for residents&#8217; shared activities.<\/li>\n<li>Residents shape their neighborhood to reflect their own preferences. Community in our buildings is built by the residents. <\/li>\n<li>Setlementtiasunnot supports residents in challenging housing-related situations as well as in shared activities.<\/li>\n<li>Our buildings also host external operators who offer diverse programs, such as mother-child circle activities. You can always suggest more! <\/li>\n<li>Through the Kerro resident application, residents can book our building&#8217;s facilities and services. The application also serves as an information channel. <\/li>\n<\/ul>\n<p>The resident committee and residents can jointly organize various events in the facilities and make the activities their own. Residents jointly organize, for example, cultural and nature trips, brunches and pre-Christmas parties, art exhibitions, soup clubs, and exercise classes. Many of our residents have found new friends through these events.  <\/p>\n<p>Community in the building is everyone&#8217;s own choice \u2013 you can live in your own home as you wish and decide for yourself whether you want to participate in neighborhood activities.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffedc8&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_single_testimonial testimonial_style=&#8221;small_modern&#8221; text_color=&#8221;#284c79&#8243; color=&#8221;Default&#8221; quote=&#8221;Doing things together gets people off their couches, to get to know each other, and to try new things. Among other things, we go on joint excursions with residents from other buildings. &#8220;][nectar_single_testimonial testimonial_style=&#8221;small_modern&#8221; text_color=&#8221;#284c79&#8243; color=&#8221;Default&#8221; quote=&#8221;In a normal building, you don&#039;t get to know your neighbors; here, you do.&#8221;][nectar_single_testimonial testimonial_style=&#8221;small_modern&#8221; text_color=&#8221;#284c79&#8243; color=&#8221;Default&#8221; quote=&#8221;Setlementtiasunnot sees people instead of just buildings.&#8221;][\/vc_column_inner][\/vc_row_inner][\/toggle][toggle color=&#8221;Extra-Color-1&#8243; heading_tag=&#8221;h4&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Ecology&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]With us, you can live responsibly. Environmental responsibility is part of all our operations. We monitor and reduce environmental impact, as well as waste, water, and energy costs. We are an environmentally responsible operator, and we make our environmental work visible. We operate within a responsible partnership network.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5>The EcoCompass environmental system guides our operations<\/h5>\n<i class=\"icon-tiny fa fa-external-link accent-color\"><\/i> <a href=\"https:\/\/ekokompassi.fi\/\" target=\"_blank\" rel=\"noopener\">Read more about EcoCompass<\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;2984&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Energy Efficiency<\/strong><\/p>\n<p>We use the <strong>Fiksuvesi<\/strong> system, which helps us save on residents&#8217; water bills and conserve water.<\/p>\n<p>With the <strong>E-gain system<\/strong>, we optimize energy consumption in our buildings. The system utilizes data from our buildings via sensors.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Responsible Procurement and Subcontracting<\/strong><\/p>\n<p>Our goal is increasingly responsible procurement. By finding responsible subcontractors, we build a cooperation network that aligns with our own values, such as ecology and community. <\/p>\n<p>At the same time, we create markets for companies that exemplify social responsibility and for products and services whose responsibility exceeds the minimum level defined by legislation.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Communication and Influence<\/strong><\/p>\n<p>Through our own <strong>Kerro resident application<\/strong>, we can improve our environmental communication and give residents opportunities to share their own eco-tips.<\/p>\n<p>A few Eco-Committees are already active in our buildings, and more are being established![\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;horizontal&#8221; column_element_alignment=&#8221;center&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#d7f0e0&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5>RTS environmental classification guides our construction<\/h5>\n<p>We want our buildings to be constructed responsibly. We use the <a href=\"https:\/\/cer.rts.fi\/rts-ymparistoluokitus\/\" target=\"_blank\" rel=\"noreferrer noopener\">RTS environmental classification<\/a>, which guides our construction towards sustainability. We consider the construction process, energy use, environment, indoor air, and health.[\/vc_column_text][image_with_animation image_url=&#8221;3005&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/toggle][\/toggles][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;6849&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;10%&#8221; top_padding_tablet=&#8221;10%&#8221; bottom_padding_tablet=&#8221;15%&#8221; bottom_padding_phone=&#8221;20%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#000000&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221;&#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10133","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Company - Setlementtiasunnot<\/title>\n<meta name=\"description\" content=\"Company Founded in 2000, Setlementtiasunnot builds homes, communities, and a sustainable future. We offer affordable rental homes and communal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/setlementtiasunnot.fi\/en\/company\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Company - Setlementtiasunnot\" \/>\n<meta property=\"og:description\" content=\"Company Founded in 2000, Setlementtiasunnot builds homes, communities, and a sustainable future. We offer affordable rental homes and communal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/setlementtiasunnot.fi\/en\/company\" \/>\n<meta property=\"og:site_name\" content=\"Setlementtiasunnot\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/setlementtiasunnot\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T09:06:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/setlementtiasunnot-og-1.png?wsr\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@setlementtiasuu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/company\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/company\",\"name\":\"Company - Setlementtiasunnot\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#website\"},\"datePublished\":\"2025-02-19T11:12:53+00:00\",\"dateModified\":\"2026-02-06T09:06:42+00:00\",\"description\":\"Company Founded in 2000, Setlementtiasunnot builds homes, communities, and a sustainable future. We offer affordable rental homes and communal\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/company#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/company\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/company#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Company\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#website\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\",\"name\":\"Setlementtiasunnot\",\"description\":\"L&ouml;yd&auml; toiveidesi koti\",\"publisher\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#organization\",\"name\":\"Setlementtiasunnot\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/setlementtiasunnot-og-1.png\",\"contentUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/setlementtiasunnot-og-1.png\",\"width\":1200,\"height\":630,\"caption\":\"Setlementtiasunnot\"},\"image\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/setlementtiasunnot\",\"https:\\\/\\\/x.com\\\/setlementtiasuu\",\"https:\\\/\\\/www.instagram.com\\\/setlementtiasunnot\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/setlementtiasunnot\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkTnh81yNN7k1kTsjfjIM0g\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Company - Setlementtiasunnot","description":"Company Founded in 2000, Setlementtiasunnot builds homes, communities, and a sustainable future. We offer affordable rental homes and communal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/setlementtiasunnot.fi\/en\/company","og_locale":"en_US","og_type":"article","og_title":"Company - Setlementtiasunnot","og_description":"Company Founded in 2000, Setlementtiasunnot builds homes, communities, and a sustainable future. We offer affordable rental homes and communal","og_url":"https:\/\/setlementtiasunnot.fi\/en\/company","og_site_name":"Setlementtiasunnot","article_publisher":"https:\/\/www.facebook.com\/setlementtiasunnot","article_modified_time":"2026-02-06T09:06:42+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/setlementtiasunnot-og-1.png?wsr","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@setlementtiasuu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/setlementtiasunnot.fi\/en\/company","url":"https:\/\/setlementtiasunnot.fi\/en\/company","name":"Company - Setlementtiasunnot","isPartOf":{"@id":"https:\/\/setlementtiasunnot.fi\/en#website"},"datePublished":"2025-02-19T11:12:53+00:00","dateModified":"2026-02-06T09:06:42+00:00","description":"Company Founded in 2000, Setlementtiasunnot builds homes, communities, and a sustainable future. We offer affordable rental homes and communal","breadcrumb":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/company#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/setlementtiasunnot.fi\/en\/company"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/setlementtiasunnot.fi\/en\/company#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/setlementtiasunnot.fi\/en"},{"@type":"ListItem","position":2,"name":"Company"}]},{"@type":"WebSite","@id":"https:\/\/setlementtiasunnot.fi\/en#website","url":"https:\/\/setlementtiasunnot.fi\/en","name":"Setlementtiasunnot","description":"L&ouml;yd&auml; toiveidesi koti","publisher":{"@id":"https:\/\/setlementtiasunnot.fi\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/setlementtiasunnot.fi\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/setlementtiasunnot.fi\/en#organization","name":"Setlementtiasunnot","url":"https:\/\/setlementtiasunnot.fi\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/logo\/image\/","url":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/setlementtiasunnot-og-1.png","contentUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/setlementtiasunnot-og-1.png","width":1200,"height":630,"caption":"Setlementtiasunnot"},"image":{"@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/setlementtiasunnot","https:\/\/x.com\/setlementtiasuu","https:\/\/www.instagram.com\/setlementtiasunnot\/","https:\/\/www.linkedin.com\/company\/setlementtiasunnot\/","https:\/\/www.youtube.com\/channel\/UCkTnh81yNN7k1kTsjfjIM0g"]}]}},"_links":{"self":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/pages\/10133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/comments?post=10133"}],"version-history":[{"count":10,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/pages\/10133\/revisions"}],"predecessor-version":[{"id":10167,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/pages\/10133\/revisions\/10167"}],"wp:attachment":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/media?parent=10133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}