{"id":10032,"date":"2023-09-01T09:52:30","date_gmt":"2023-09-01T06:52:30","guid":{"rendered":"https:\/\/setlementtiasunnot.fi\/our-residents-view-photo-gallery"},"modified":"2026-02-06T10:52:14","modified_gmt":"2026-02-06T08:52:14","slug":"our-residents-view-photo-gallery","status":"publish","type":"post","link":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery","title":{"rendered":"Our Residents \u2013 View Photo Gallery"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-peli.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"801\" data-id=\"5941\" src=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-peli-1200x801.jpg\" alt=\"Playing in Setlementtiasunnot's Resident Common Room\" class=\"wp-image-5941\" srcset=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-peli-1200x801.jpg 1200w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-peli-600x401.jpg 600w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-peli-768x513.jpg 768w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-peli-1536x1025.jpg 1536w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-peli.jpg 2000w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-keittio.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"801\" data-id=\"5927\" src=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-keittio-1200x801.jpg\" alt=\"Baking in Setlementtiasunnot's Resident Common Room\" class=\"wp-image-5927\" srcset=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-keittio-1200x801.jpg 1200w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-keittio-600x401.jpg 600w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-keittio-768x513.jpg 768w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-keittio-1536x1025.jpg 1536w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-keittio.jpg 2000w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-peili.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"801\" data-id=\"5939\" src=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-peili-1200x801.jpg\" alt=\"Mirror Reflection in Setlementtiasunnot's Sauna Facility\" class=\"wp-image-5939\" srcset=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-peili-1200x801.jpg 1200w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-peili-600x401.jpg 600w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-peili-768x513.jpg 768w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-peili-1536x1025.jpg 1536w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-peili.jpg 2000w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-_kirjasto.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"801\" data-id=\"5935\" src=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-_kirjasto-1200x801.jpg\" alt=\"Setlementtiasunnot's Resident Library\" class=\"wp-image-5935\" srcset=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-_kirjasto-1200x801.jpg 1200w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-_kirjasto-600x401.jpg 600w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-_kirjasto-768x513.jpg 768w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-_kirjasto-1536x1025.jpg 1536w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-_kirjasto.jpg 2000w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-kahvit.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"801\" data-id=\"5937\" src=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-kahvit-1200x801.jpg\" alt=\"Residents Having Coffee\" class=\"wp-image-5937\" srcset=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-kahvit-1200x801.jpg 1200w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-kahvit-600x401.jpg 600w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-kahvit-768x513.jpg 768w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-kahvit-1536x1025.jpg 1536w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-kahvit.jpg 2000w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure>\n<\/figure>\n\n<p><\/p>\n\n<p>We have been photographing the residents of our buildings during the summer. Here are the first impressions of residents&#8217; everyday life at Setlementtiasunnot \u2013 perhaps in your own area. Cooking, playing in the common room, and enjoying a summer day in the courtyard.  <\/p>\n\n<p>We will showcase more of our residents&#8217; lives later.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"801\" src=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-grilli-1200x801.jpg\" alt=\"Setlementtiasunnot's Barbecue Shelter\" class=\"wp-image-5929\" srcset=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-grilli-1200x801.jpg 1200w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-grilli-600x401.jpg 600w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-grilli-768x513.jpg 768w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-grilli-1536x1025.jpg 1536w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-grilli.jpg 2000w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>We have been photographing the residents of our buildings during the summer. Here are the first impressions of residents&#8217; everyday life at Setlementtiasunnot \u2013 perhaps in your own area. Cooking,&#8230;<\/p>\n","protected":false},"author":16,"featured_media":5931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1116],"tags":[],"class_list":{"0":"post-10032","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Our Residents \u2013 View Photo Gallery - Setlementtiasunnot<\/title>\n<meta name=\"description\" content=\"View a photo gallery of residents&#039; everyday life at Setlementtiasunnot \u2013 perhaps in your own area.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our Residents \u2013 View Photo Gallery - Setlementtiasunnot\" \/>\n<meta property=\"og:description\" content=\"View a photo gallery of residents&#039; everyday life at Setlementtiasunnot \u2013 perhaps in your own area.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery\" \/>\n<meta property=\"og:site_name\" content=\"Setlementtiasunnot\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/setlementtiasunnot\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-01T06:52:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T08:52:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-peli.jpg?wsr\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Minna Jerrman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@setlementtiasuu\" \/>\n<meta name=\"twitter:site\" content=\"@setlementtiasuu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery\"},\"author\":{\"name\":\"Minna Jerrman\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/person\\\/f53368dd67e6f889a68f1c8f481eec77\"},\"headline\":\"Our Residents \u2013 View Photo Gallery\",\"datePublished\":\"2023-09-01T06:52:30+00:00\",\"dateModified\":\"2026-02-06T08:52:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery\"},\"wordCount\":56,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/Asukaskuvaus-1-piha.jpg?wsr\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery\",\"name\":\"Our Residents \u2013 View Photo Gallery - Setlementtiasunnot\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/Asukaskuvaus-1-piha.jpg?wsr\",\"datePublished\":\"2023-09-01T06:52:30+00:00\",\"dateModified\":\"2026-02-06T08:52:14+00:00\",\"description\":\"View a photo gallery of residents' everyday life at Setlementtiasunnot \u2013 perhaps in your own area.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery#primaryimage\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/Asukaskuvaus-1-piha.jpg?wsr\",\"contentUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/Asukaskuvaus-1-piha.jpg?wsr\",\"width\":2000,\"height\":1335},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/our-residents-view-photo-gallery#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our Residents \u2013 View Photo Gallery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#website\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\",\"name\":\"Setlementtiasunnot\",\"description\":\"L&ouml;yd&auml; toiveidesi koti\",\"publisher\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#organization\",\"name\":\"Setlementtiasunnot\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/setlementtiasunnot-og-1.png\",\"contentUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/setlementtiasunnot-og-1.png\",\"width\":1200,\"height\":630,\"caption\":\"Setlementtiasunnot\"},\"image\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/setlementtiasunnot\",\"https:\\\/\\\/x.com\\\/setlementtiasuu\",\"https:\\\/\\\/www.instagram.com\\\/setlementtiasunnot\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/setlementtiasunnot\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkTnh81yNN7k1kTsjfjIM0g\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/person\\\/f53368dd67e6f889a68f1c8f481eec77\",\"name\":\"Minna Jerrman\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Our Residents \u2013 View Photo Gallery - Setlementtiasunnot","description":"View a photo gallery of residents' everyday life at Setlementtiasunnot \u2013 perhaps in your own area.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery","og_locale":"en_US","og_type":"article","og_title":"Our Residents \u2013 View Photo Gallery - Setlementtiasunnot","og_description":"View a photo gallery of residents' everyday life at Setlementtiasunnot \u2013 perhaps in your own area.","og_url":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery","og_site_name":"Setlementtiasunnot","article_publisher":"https:\/\/www.facebook.com\/setlementtiasunnot","article_published_time":"2023-09-01T06:52:30+00:00","article_modified_time":"2026-02-06T08:52:14+00:00","og_image":[{"width":2000,"height":1335,"url":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-asukastila-peli.jpg?wsr","type":"image\/jpeg"}],"author":"Minna Jerrman","twitter_card":"summary_large_image","twitter_creator":"@setlementtiasuu","twitter_site":"@setlementtiasuu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery#article","isPartOf":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery"},"author":{"name":"Minna Jerrman","@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/person\/f53368dd67e6f889a68f1c8f481eec77"},"headline":"Our Residents \u2013 View Photo Gallery","datePublished":"2023-09-01T06:52:30+00:00","dateModified":"2026-02-06T08:52:14+00:00","mainEntityOfPage":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery"},"wordCount":56,"commentCount":0,"publisher":{"@id":"https:\/\/setlementtiasunnot.fi\/en#organization"},"image":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery#primaryimage"},"thumbnailUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-piha.jpg?wsr","articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery#respond"]}]},{"@type":"WebPage","@id":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery","url":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery","name":"Our Residents \u2013 View Photo Gallery - Setlementtiasunnot","isPartOf":{"@id":"https:\/\/setlementtiasunnot.fi\/en#website"},"primaryImageOfPage":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery#primaryimage"},"image":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery#primaryimage"},"thumbnailUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-piha.jpg?wsr","datePublished":"2023-09-01T06:52:30+00:00","dateModified":"2026-02-06T08:52:14+00:00","description":"View a photo gallery of residents' everyday life at Setlementtiasunnot \u2013 perhaps in your own area.","breadcrumb":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery#primaryimage","url":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-piha.jpg?wsr","contentUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/Asukaskuvaus-1-piha.jpg?wsr","width":2000,"height":1335},{"@type":"BreadcrumbList","@id":"https:\/\/setlementtiasunnot.fi\/en\/our-residents-view-photo-gallery#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/setlementtiasunnot.fi\/en"},{"@type":"ListItem","position":2,"name":"Our Residents \u2013 View Photo Gallery"}]},{"@type":"WebSite","@id":"https:\/\/setlementtiasunnot.fi\/en#website","url":"https:\/\/setlementtiasunnot.fi\/en","name":"Setlementtiasunnot","description":"L&ouml;yd&auml; toiveidesi koti","publisher":{"@id":"https:\/\/setlementtiasunnot.fi\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/setlementtiasunnot.fi\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/setlementtiasunnot.fi\/en#organization","name":"Setlementtiasunnot","url":"https:\/\/setlementtiasunnot.fi\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/logo\/image\/","url":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/setlementtiasunnot-og-1.png","contentUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/setlementtiasunnot-og-1.png","width":1200,"height":630,"caption":"Setlementtiasunnot"},"image":{"@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/setlementtiasunnot","https:\/\/x.com\/setlementtiasuu","https:\/\/www.instagram.com\/setlementtiasunnot\/","https:\/\/www.linkedin.com\/company\/setlementtiasunnot\/","https:\/\/www.youtube.com\/channel\/UCkTnh81yNN7k1kTsjfjIM0g"]},{"@type":"Person","@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/person\/f53368dd67e6f889a68f1c8f481eec77","name":"Minna Jerrman"}]}},"_links":{"self":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/posts\/10032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/comments?post=10032"}],"version-history":[{"count":1,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/posts\/10032\/revisions"}],"predecessor-version":[{"id":10033,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/posts\/10032\/revisions\/10033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/media\/5931"}],"wp:attachment":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/media?parent=10032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/categories?post=10032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/tags?post=10032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}