{"id":10056,"date":"2023-06-16T09:04:01","date_gmt":"2023-06-16T06:04:01","guid":{"rendered":"https:\/\/setlementtiasunnot.fi\/postipuisto-community-center-has-opened"},"modified":"2026-02-06T10:53:10","modified_gmt":"2026-02-06T08:53:10","slug":"postipuisto-community-center-has-opened","status":"publish","type":"post","link":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened","title":{"rendered":"Postipuisto Community Center has opened"},"content":{"rendered":"\n<p>The community center for our residents in <a href=\"https:\/\/setlementtiasunnot.fi\/postipuiston-setlementtiasunnot\/\">Postipuisto<\/a> has opened at Rullakkokatu 2. The community center has been named Postivariko. <\/p>\n\n<p>Residents now have access to a sports hall, a gym, a workspace and performance area, a multi-purpose room, and a workshop, among other facilities. Courses, such as fitness boxing and Pilates, are also organized in these spaces. Additionally, the facilities can be reserved for private use, for example, for family celebrations or meetings. Private reservations are subject to a fee.   <\/p>\n\n<p>\u2013 What is special about the community center is how it brings all residents of the area closer together, thereby helping to form a more cohesive regional community, says <strong>Eemeli L\u00f6nnqvist<\/strong>, Property Director at Setlementtiasunnot, pleased with the shared-use building.<\/p>\n\n<p>\u2013 Furthermore, the shared-use building includes a much wider selection of high-quality facilities than would be cost-effective to implement in a single apartment building or block. For the affordability of our residents, we truly gain added value with this kind of concept, L\u00f6nnqvist states. <\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" data-id=\"5438\" src=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/monitoimitila-2000-1200x800.jpg\" alt=\"\" class=\"wp-image-5438\" srcset=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/monitoimitila-2000-1200x800.jpg 1200w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/monitoimitila-2000-600x400.jpg 600w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/monitoimitila-2000-768x512.jpg 768w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/monitoimitila-2000-1536x1025.jpg 1536w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/monitoimitila-2000.jpg 2000w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Multi-purpose room<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" data-id=\"5436\" src=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/liikuntasali-2000-1200x800.jpg\" alt=\"\" class=\"wp-image-5436\" srcset=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/liikuntasali-2000-1200x800.jpg 1200w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/liikuntasali-2000-600x400.jpg 600w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/liikuntasali-2000-768x512.jpg 768w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/liikuntasali-2000-1536x1025.jpg 1536w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/liikuntasali-2000.jpg 2000w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Sports hall<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" data-id=\"5434\" src=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/kuntosali1-2000-1200x800.jpg\" alt=\"\" class=\"wp-image-5434\" srcset=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/kuntosali1-2000-1200x800.jpg 1200w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/kuntosali1-2000-600x400.jpg 600w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/kuntosali1-2000-768x512.jpg 768w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/kuntosali1-2000-1536x1025.jpg 1536w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/kuntosali1-2000.jpg 2000w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Gym<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" data-id=\"5442\" src=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/verstas2-2000-1200x800.jpg\" alt=\"\" class=\"wp-image-5442\" srcset=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/verstas2-2000-1200x800.jpg 1200w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/verstas2-2000-600x400.jpg 600w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/verstas2-2000-768x512.jpg 768w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/verstas2-2000-1536x1025.jpg 1536w, https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/verstas2-2000.jpg 2000w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Workshop<\/figcaption><\/figure>\n<\/figure>\n\n<h2 class=\"wp-block-heading\">Register for the booking service<\/h2>\n\n<p>Residents can access the facilities using personal electronic access codes, which they receive through the Postivariko booking service. Therefore, if you wish to use Postivariko&#8217;s facilities, please register as a user of the <a href=\"https:\/\/postivarikko.fi\" target=\"_blank\" rel=\"noreferrer noopener\">Postivariko booking service<\/a>.  <\/p>\n\n<p>On the booking service website, you will also find the community center&#8217;s opening hours and information about Postivariko&#8217;s events, courses, and other activities.<\/p>\n\n<p><\/p>\n\n<p><em>The <a href=\"https:\/\/setlementtiasunnot.fi\/postipuiston-setlementtiasunnot\/\">Postipuisto building in Helsinki<\/a> has a total of 88 apartments, 17 of which are intended for residents aged 55+. The building was completed in 2022. <\/em><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The community center for our residents in Postipuisto has opened at Rullakkokatu 2. The community center has been named Postivariko. Residents now have access to a sports hall, a gym,&#8230;<\/p>\n","protected":false},"author":16,"featured_media":5440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1116],"tags":[916],"class_list":{"0":"post-10056","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"tag-postipuisto"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Postipuisto Community Center has opened - Setlementtiasunnot<\/title>\n<meta name=\"description\" content=\"The community center for our residents in Postipuisto has opened at Rullakkokatu 2. The community center has been named Postivariko. Residents now have\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Postipuisto Community Center has opened - Setlementtiasunnot\" \/>\n<meta property=\"og:description\" content=\"The community center for our residents in Postipuisto has opened at Rullakkokatu 2. The community center has been named Postivariko. Residents now have\" \/>\n<meta property=\"og:url\" content=\"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened\" \/>\n<meta property=\"og:site_name\" content=\"Setlementtiasunnot\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/setlementtiasunnot\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-16T06:04:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T08:53:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/monitoimitila-2000-1200x800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Minna Jerrman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@setlementtiasuu\" \/>\n<meta name=\"twitter:site\" content=\"@setlementtiasuu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened\"},\"author\":{\"name\":\"Minna Jerrman\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/person\\\/f53368dd67e6f889a68f1c8f481eec77\"},\"headline\":\"Postipuisto Community Center has opened\",\"datePublished\":\"2023-06-16T06:04:01+00:00\",\"dateModified\":\"2026-02-06T08:53:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened\"},\"wordCount\":263,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/paasisaankaynti-ulkoa-2000.jpg?wsr\",\"keywords\":[\"Postipuisto\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened\",\"name\":\"Postipuisto Community Center has opened - Setlementtiasunnot\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/paasisaankaynti-ulkoa-2000.jpg?wsr\",\"datePublished\":\"2023-06-16T06:04:01+00:00\",\"dateModified\":\"2026-02-06T08:53:10+00:00\",\"description\":\"The community center for our residents in Postipuisto has opened at Rullakkokatu 2. The community center has been named Postivariko. Residents now have\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened#primaryimage\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/paasisaankaynti-ulkoa-2000.jpg?wsr\",\"contentUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/paasisaankaynti-ulkoa-2000.jpg?wsr\",\"width\":2500,\"height\":1668},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/postipuisto-community-center-has-opened#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Postipuisto Community Center has opened\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#website\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\",\"name\":\"Setlementtiasunnot\",\"description\":\"L&ouml;yd&auml; toiveidesi koti\",\"publisher\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#organization\",\"name\":\"Setlementtiasunnot\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/setlementtiasunnot-og-1.png\",\"contentUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/setlementtiasunnot-og-1.png\",\"width\":1200,\"height\":630,\"caption\":\"Setlementtiasunnot\"},\"image\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/setlementtiasunnot\",\"https:\\\/\\\/x.com\\\/setlementtiasuu\",\"https:\\\/\\\/www.instagram.com\\\/setlementtiasunnot\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/setlementtiasunnot\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkTnh81yNN7k1kTsjfjIM0g\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/person\\\/f53368dd67e6f889a68f1c8f481eec77\",\"name\":\"Minna Jerrman\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Postipuisto Community Center has opened - Setlementtiasunnot","description":"The community center for our residents in Postipuisto has opened at Rullakkokatu 2. The community center has been named Postivariko. Residents now have","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened","og_locale":"en_US","og_type":"article","og_title":"Postipuisto Community Center has opened - Setlementtiasunnot","og_description":"The community center for our residents in Postipuisto has opened at Rullakkokatu 2. The community center has been named Postivariko. Residents now have","og_url":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened","og_site_name":"Setlementtiasunnot","article_publisher":"https:\/\/www.facebook.com\/setlementtiasunnot","article_published_time":"2023-06-16T06:04:01+00:00","article_modified_time":"2026-02-06T08:53:10+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/monitoimitila-2000-1200x800.jpg","type":"image\/jpeg"}],"author":"Minna Jerrman","twitter_card":"summary_large_image","twitter_creator":"@setlementtiasuu","twitter_site":"@setlementtiasuu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened#article","isPartOf":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened"},"author":{"name":"Minna Jerrman","@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/person\/f53368dd67e6f889a68f1c8f481eec77"},"headline":"Postipuisto Community Center has opened","datePublished":"2023-06-16T06:04:01+00:00","dateModified":"2026-02-06T08:53:10+00:00","mainEntityOfPage":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened"},"wordCount":263,"commentCount":0,"publisher":{"@id":"https:\/\/setlementtiasunnot.fi\/en#organization"},"image":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened#primaryimage"},"thumbnailUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/paasisaankaynti-ulkoa-2000.jpg?wsr","keywords":["Postipuisto"],"articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened#respond"]}]},{"@type":"WebPage","@id":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened","url":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened","name":"Postipuisto Community Center has opened - Setlementtiasunnot","isPartOf":{"@id":"https:\/\/setlementtiasunnot.fi\/en#website"},"primaryImageOfPage":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened#primaryimage"},"image":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened#primaryimage"},"thumbnailUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/paasisaankaynti-ulkoa-2000.jpg?wsr","datePublished":"2023-06-16T06:04:01+00:00","dateModified":"2026-02-06T08:53:10+00:00","description":"The community center for our residents in Postipuisto has opened at Rullakkokatu 2. The community center has been named Postivariko. Residents now have","breadcrumb":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened#primaryimage","url":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/paasisaankaynti-ulkoa-2000.jpg?wsr","contentUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/paasisaankaynti-ulkoa-2000.jpg?wsr","width":2500,"height":1668},{"@type":"BreadcrumbList","@id":"https:\/\/setlementtiasunnot.fi\/en\/postipuisto-community-center-has-opened#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/setlementtiasunnot.fi\/en"},{"@type":"ListItem","position":2,"name":"Postipuisto Community Center has opened"}]},{"@type":"WebSite","@id":"https:\/\/setlementtiasunnot.fi\/en#website","url":"https:\/\/setlementtiasunnot.fi\/en","name":"Setlementtiasunnot","description":"L&ouml;yd&auml; toiveidesi koti","publisher":{"@id":"https:\/\/setlementtiasunnot.fi\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/setlementtiasunnot.fi\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/setlementtiasunnot.fi\/en#organization","name":"Setlementtiasunnot","url":"https:\/\/setlementtiasunnot.fi\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/logo\/image\/","url":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/setlementtiasunnot-og-1.png","contentUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/setlementtiasunnot-og-1.png","width":1200,"height":630,"caption":"Setlementtiasunnot"},"image":{"@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/setlementtiasunnot","https:\/\/x.com\/setlementtiasuu","https:\/\/www.instagram.com\/setlementtiasunnot\/","https:\/\/www.linkedin.com\/company\/setlementtiasunnot\/","https:\/\/www.youtube.com\/channel\/UCkTnh81yNN7k1kTsjfjIM0g"]},{"@type":"Person","@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/person\/f53368dd67e6f889a68f1c8f481eec77","name":"Minna Jerrman"}]}},"_links":{"self":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/posts\/10056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/comments?post=10056"}],"version-history":[{"count":1,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/posts\/10056\/revisions"}],"predecessor-version":[{"id":10057,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/posts\/10056\/revisions\/10057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/media\/5440"}],"wp:attachment":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/media?parent=10056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/categories?post=10056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/tags?post=10056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}