{"id":10257,"date":"2019-12-20T10:47:57","date_gmt":"2019-12-20T08:47:57","guid":{"rendered":"https:\/\/setlementtiasunnot.fi\/malmis-bright-spot"},"modified":"2026-02-06T11:07:04","modified_gmt":"2026-02-06T09:07:04","slug":"malmis-bright-spot","status":"publish","type":"post","link":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot","title":{"rendered":"Malmi&#8217;s Bright Spot"},"content":{"rendered":"\n<h6 class=\"wp-block-heading\">The year is now at its darkest point. If you have been in Malmi, Helsinki, you may have encountered this bright spot. The traditional fluorescent tubes at Setlementtiasunnot Malmi have been replaced with LED lights, and the result is stunningly beautiful. The building is designed so that the lights are always on during dark hours, illuminating the building&#8217;s colors.   <\/h6>\n\n<p>The lights are not only impressive but also an ecological act. Compared to energy-saving lamps, LED lights consume 50 percent less energy. They also do not contain mercury and are long-lasting.  <\/p>\n\n<p>In addition to lighting, ecological considerations are evident at Setlementtiasunnot in many other ways. The EcoCompass environmental system, in use since 2018, has helped improve areas crucial for Setlementtiasunnot: energy management, recycling, and resident communication. <\/p>\n\n<p>Photo: Jyri Bj\u00f6rninen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The year is now at its darkest point. If you have been in Malmi, Helsinki, you may have encountered this bright spot. The traditional fluorescent tubes at Setlementtiasunnot Malmi have&#8230;<\/p>\n","protected":false},"author":15,"featured_media":1002,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1118],"tags":[],"class_list":{"0":"post-10257","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-residents-corner"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Malmi&#039;s Bright Spot - Setlementtiasunnot<\/title>\n<meta name=\"description\" content=\"The year is now at its darkest point. If you have been in Malmi, Helsinki, you may have encountered this bright spot. The traditional fluorescent tubes at\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Malmi&#039;s Bright Spot - Setlementtiasunnot\" \/>\n<meta property=\"og:description\" content=\"The year is now at its darkest point. If you have been in Malmi, Helsinki, you may have encountered this bright spot. The traditional fluorescent tubes at\" \/>\n<meta property=\"og:url\" content=\"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot\" \/>\n<meta property=\"og:site_name\" content=\"Setlementtiasunnot\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/setlementtiasunnot\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-20T08:47:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T09:07:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/setlementtiasunnot-og-1.png?wsr\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Anette Salin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@setlementtiasuu\" \/>\n<meta name=\"twitter:site\" content=\"@setlementtiasuu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/malmis-bright-spot#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/malmis-bright-spot\"},\"author\":{\"name\":\"Anette Salin\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/person\\\/b00c9c3bd8eed842aca4230c9b4a7e45\"},\"headline\":\"Malmi&#8217;s Bright Spot\",\"datePublished\":\"2019-12-20T08:47:57+00:00\",\"dateModified\":\"2026-02-06T09:07:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/malmis-bright-spot\"},\"wordCount\":132,\"publisher\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/malmis-bright-spot#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/IMG_20191126_194400-1536x1152-1.jpg?wsr\",\"articleSection\":[\"Resident&#039;s Corner\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/malmis-bright-spot\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/malmis-bright-spot\",\"name\":\"Malmi's Bright Spot - Setlementtiasunnot\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/malmis-bright-spot#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/malmis-bright-spot#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/IMG_20191126_194400-1536x1152-1.jpg?wsr\",\"datePublished\":\"2019-12-20T08:47:57+00:00\",\"dateModified\":\"2026-02-06T09:07:04+00:00\",\"description\":\"The year is now at its darkest point. If you have been in Malmi, Helsinki, you may have encountered this bright spot. The traditional fluorescent tubes at\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/malmis-bright-spot#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/malmis-bright-spot\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/malmis-bright-spot#primaryimage\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/IMG_20191126_194400-1536x1152-1.jpg?wsr\",\"contentUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/IMG_20191126_194400-1536x1152-1.jpg?wsr\",\"width\":1536,\"height\":1152,\"caption\":\"Kuva: Jyri Br\u00f6rninen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\\\/malmis-bright-spot#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Malmi&#8217;s Bright Spot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#website\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\",\"name\":\"Setlementtiasunnot\",\"description\":\"L&ouml;yd&auml; toiveidesi koti\",\"publisher\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#organization\",\"name\":\"Setlementtiasunnot\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/setlementtiasunnot-og-1.png\",\"contentUrl\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/wp-content\\\/uploads\\\/setlementtiasunnot-og-1.png\",\"width\":1200,\"height\":630,\"caption\":\"Setlementtiasunnot\"},\"image\":{\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/setlementtiasunnot\",\"https:\\\/\\\/x.com\\\/setlementtiasuu\",\"https:\\\/\\\/www.instagram.com\\\/setlementtiasunnot\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/setlementtiasunnot\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkTnh81yNN7k1kTsjfjIM0g\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/setlementtiasunnot.fi\\\/en#\\\/schema\\\/person\\\/b00c9c3bd8eed842aca4230c9b4a7e45\",\"name\":\"Anette Salin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Malmi's Bright Spot - Setlementtiasunnot","description":"The year is now at its darkest point. If you have been in Malmi, Helsinki, you may have encountered this bright spot. The traditional fluorescent tubes at","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot","og_locale":"en_US","og_type":"article","og_title":"Malmi's Bright Spot - Setlementtiasunnot","og_description":"The year is now at its darkest point. If you have been in Malmi, Helsinki, you may have encountered this bright spot. The traditional fluorescent tubes at","og_url":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot","og_site_name":"Setlementtiasunnot","article_publisher":"https:\/\/www.facebook.com\/setlementtiasunnot","article_published_time":"2019-12-20T08:47:57+00:00","article_modified_time":"2026-02-06T09:07:04+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/setlementtiasunnot-og-1.png?wsr","type":"image\/png"}],"author":"Anette Salin","twitter_card":"summary_large_image","twitter_creator":"@setlementtiasuu","twitter_site":"@setlementtiasuu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot#article","isPartOf":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot"},"author":{"name":"Anette Salin","@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/person\/b00c9c3bd8eed842aca4230c9b4a7e45"},"headline":"Malmi&#8217;s Bright Spot","datePublished":"2019-12-20T08:47:57+00:00","dateModified":"2026-02-06T09:07:04+00:00","mainEntityOfPage":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot"},"wordCount":132,"publisher":{"@id":"https:\/\/setlementtiasunnot.fi\/en#organization"},"image":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot#primaryimage"},"thumbnailUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/IMG_20191126_194400-1536x1152-1.jpg?wsr","articleSection":["Resident&#039;s Corner"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot","url":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot","name":"Malmi's Bright Spot - Setlementtiasunnot","isPartOf":{"@id":"https:\/\/setlementtiasunnot.fi\/en#website"},"primaryImageOfPage":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot#primaryimage"},"image":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot#primaryimage"},"thumbnailUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/IMG_20191126_194400-1536x1152-1.jpg?wsr","datePublished":"2019-12-20T08:47:57+00:00","dateModified":"2026-02-06T09:07:04+00:00","description":"The year is now at its darkest point. If you have been in Malmi, Helsinki, you may have encountered this bright spot. The traditional fluorescent tubes at","breadcrumb":{"@id":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot#primaryimage","url":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/IMG_20191126_194400-1536x1152-1.jpg?wsr","contentUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/IMG_20191126_194400-1536x1152-1.jpg?wsr","width":1536,"height":1152,"caption":"Kuva: Jyri Br\u00f6rninen"},{"@type":"BreadcrumbList","@id":"https:\/\/setlementtiasunnot.fi\/en\/malmis-bright-spot#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/setlementtiasunnot.fi\/en"},{"@type":"ListItem","position":2,"name":"Malmi&#8217;s Bright Spot"}]},{"@type":"WebSite","@id":"https:\/\/setlementtiasunnot.fi\/en#website","url":"https:\/\/setlementtiasunnot.fi\/en","name":"Setlementtiasunnot","description":"L&ouml;yd&auml; toiveidesi koti","publisher":{"@id":"https:\/\/setlementtiasunnot.fi\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/setlementtiasunnot.fi\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/setlementtiasunnot.fi\/en#organization","name":"Setlementtiasunnot","url":"https:\/\/setlementtiasunnot.fi\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/logo\/image\/","url":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/setlementtiasunnot-og-1.png","contentUrl":"https:\/\/setlementtiasunnot.fi\/wp-content\/uploads\/setlementtiasunnot-og-1.png","width":1200,"height":630,"caption":"Setlementtiasunnot"},"image":{"@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/setlementtiasunnot","https:\/\/x.com\/setlementtiasuu","https:\/\/www.instagram.com\/setlementtiasunnot\/","https:\/\/www.linkedin.com\/company\/setlementtiasunnot\/","https:\/\/www.youtube.com\/channel\/UCkTnh81yNN7k1kTsjfjIM0g"]},{"@type":"Person","@id":"https:\/\/setlementtiasunnot.fi\/en#\/schema\/person\/b00c9c3bd8eed842aca4230c9b4a7e45","name":"Anette Salin"}]}},"_links":{"self":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/posts\/10257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/comments?post=10257"}],"version-history":[{"count":1,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/posts\/10257\/revisions"}],"predecessor-version":[{"id":10258,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/posts\/10257\/revisions\/10258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/media\/1002"}],"wp:attachment":[{"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/media?parent=10257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/categories?post=10257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/setlementtiasunnot.fi\/en\/wp-json\/wp\/v2\/tags?post=10257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}